{"id":12,"date":"2016-10-04T11:29:12","date_gmt":"2016-10-04T09:29:12","guid":{"rendered":"https:\/\/www.centritecnopolo.unipr.it\/biopharmanet-tec\/?page_id=12"},"modified":"2023-03-31T16:08:44","modified_gmt":"2023-03-31T14:08:44","slug":"servizi","status":"publish","type":"page","link":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/servizi\/","title":{"rendered":"Servizi"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Attraverso le competenze delle sue <a href=\"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/il-centro\/unita-operative\/\">5 unit\u00e0 operative<\/a>, il Centro svolge <strong>attivit\u00e0 di ricerca applicata<\/strong> per lo sviluppo delle tecnologie dell&#8217;industria 4.0.<\/span><!--more--><\/p>\n<p class=\"p1\"><span class=\"s1\">R<\/span><span class=\"s2\">ealizziamo <strong>prototipi<\/strong> da utilizzare come dimostratori per le aziende operanti nelle supply-chain dei prodotti di largo consumo,<\/span><span class=\"s2\"> del settore tessile e abbigliamento, e per le pubbliche amministrazioni che intendono usufruire delle tecnologie RFID e di visione artificiale.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attraverso le competenze delle sue 5 unit\u00e0 operative, il Centro svolge attivit\u00e0 di ricerca applicata per lo sviluppo delle tecnologie [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/pages\/12"}],"collection":[{"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":6,"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":187,"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/pages\/12\/revisions\/187"}],"wp:attachment":[{"href":"https:\/\/www.centritecnopolo.unipr.it\/futuretechnologylab\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}